{"id":28,"date":"2014-08-27T15:17:00","date_gmt":"2014-08-27T14:17:00","guid":{"rendered":"https:\/\/edv-verzweifelt.de\/?p=28"},"modified":"2026-03-09T22:55:29","modified_gmt":"2026-03-09T21:55:29","slug":"danke-fuer-die-auskunft","status":"publish","type":"post","link":"https:\/\/edv-verzweifelt.de\/index.php\/2014\/08\/27\/danke-fuer-die-auskunft\/","title":{"rendered":"Danke f\u00fcr die Auskunft"},"content":{"rendered":"\n<p>&lt;Service versucht einen Mitarbeiter zur\u00fcckzurufen, um einen Ablauf abzufragen, der kurz vorher zu einem Problem gef\u00fchrt hat. Jedoch ist dieser nicht am Platz und seine Vertretung geht ans Telefon><\/p>\n\n\n\n<p><strong>Service<\/strong>:<em>&nbsp;Ist der Herr XXX wohl zu sprechen?<\/em><\/p>\n\n\n\n<p><strong>Kunde<\/strong>:&nbsp;<em>Nein, der ist gerade nicht am Platz. Kann ich Ihnen helfen?<\/em><\/p>\n\n\n\n<p><strong>Service<\/strong>:&nbsp;<em>Sie haben sicherlich mitbekommen, dass der Kollege gerade ein Problem hatte. Wissen Sie zuf\u00e4lliger weise, bei welchen Ausdruck das aufgetreten war?<\/em><\/p>\n\n\n\n<p><strong>Kunde<\/strong>:&nbsp;<em>Ich denke bei einen Ausdruck aus dem Programm \u201eProgramm1\u201c. (Name ge\u00e4ndert)<\/em><\/p>\n\n\n\n<p><strong>Service<\/strong>:&nbsp;<em>Nee das kann nicht sein, da wir nur das Programm \u201eProgramm2\u201c (Name ge\u00e4ndert) betreuen.<\/em><\/p>\n\n\n\n<p><strong>Kunde<\/strong>:&nbsp;<em>Ja genau das meinte ich auch. Dort hatte er das Problem.<\/em><\/p>\n\n\n\n<p><strong>Service<\/strong>:&nbsp;<em>Ja und wo genau dort?<\/em><\/p>\n\n\n\n<p><strong>Kunde<\/strong>:&nbsp;<em>Das weis ich leider nicht genau, ich kann ihnen aber sagen, dass der Kollege mit seinen Computer gearbeitet hat..<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;Service versucht einen Mitarbeiter zur\u00fcckzurufen, um einen Ablauf abzufragen, der kurz vorher zu einem Problem gef\u00fchrt hat. Jedoch ist dieser nicht am Platz und seine Vertretung geht ans Telefon> Service:&nbsp;Ist der Herr XXX wohl zu sprechen? Kunde:&nbsp;Nein, der ist gerade nicht am Platz. Kann ich Ihnen helfen? Service:&nbsp;Sie haben sicherlich mitbekommen, dass der Kollege gerade &hellip; <a href=\"https:\/\/edv-verzweifelt.de\/index.php\/2014\/08\/27\/danke-fuer-die-auskunft\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDanke f\u00fcr die Auskunft\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":1,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"predecessor-version":[{"id":29,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/28\/revisions\/29"}],"wp:attachment":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}