{"id":48,"date":"2013-01-04T15:27:00","date_gmt":"2013-01-04T14:27:00","guid":{"rendered":"https:\/\/edv-verzweifelt.de\/?p=48"},"modified":"2026-03-09T22:55:40","modified_gmt":"2026-03-09T21:55:40","slug":"andere-laender-andere-schwierigkeiten","status":"publish","type":"post","link":"https:\/\/edv-verzweifelt.de\/index.php\/2013\/01\/04\/andere-laender-andere-schwierigkeiten\/","title":{"rendered":"Andere L\u00e4nder, andere Schwierigkeiten"},"content":{"rendered":"\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ich habe gerade ein paar E-Mails bekommen.<\/em><\/p>\n\n\n\n<p><strong>Service:&nbsp;<\/strong><em>Soweit so gut. Was ist dabei das Problem?<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Die sind auf Franz\u00f6sisch!<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>OK. Aber was ist das Problem dabei?<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ich kann kein Franz\u00f6sisch. Von daher habe ich gedacht, da es sich ja um E-Mails handeln rufe ich mal bei der IT an. Vielleicht k\u00f6nnten Sie mir diese \u00fcbersetzen!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde:&nbsp;Ich habe gerade ein paar E-Mails bekommen. Service:&nbsp;Soweit so gut. Was ist dabei das Problem? Kunde:&nbsp;Die sind auf Franz\u00f6sisch! Service:&nbsp;OK. Aber was ist das Problem dabei? Kunde:&nbsp;Ich kann kein Franz\u00f6sisch. Von daher habe ich gedacht, da es sich ja um E-Mails handeln rufe ich mal bei der IT an. Vielleicht k\u00f6nnten Sie mir diese \u00fcbersetzen!<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/comments?post=48"}],"version-history":[{"count":1,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/48\/revisions"}],"predecessor-version":[{"id":49,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/48\/revisions\/49"}],"wp:attachment":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/media?parent=48"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/categories?post=48"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/tags?post=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}