{"id":54,"date":"2012-07-18T15:29:00","date_gmt":"2012-07-18T14:29:00","guid":{"rendered":"https:\/\/edv-verzweifelt.de\/?p=54"},"modified":"2026-03-09T22:55:40","modified_gmt":"2026-03-09T21:55:40","slug":"warten-wirs-ab-aber-fang-schonmal-an","status":"publish","type":"post","link":"https:\/\/edv-verzweifelt.de\/index.php\/2012\/07\/18\/warten-wirs-ab-aber-fang-schonmal-an\/","title":{"rendered":"Warten wir\u2019s ab aber fang schonmal an"},"content":{"rendered":"\n<p><strong>Kunde:<\/strong>&nbsp;Kannst du mal nachschauen, ob eine Referenz an den Zoll \u00fcbergeben wurde?<\/p>\n\n\n\n<p><strong>Service:&nbsp;<\/strong><em>Ja klar.<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Was brauchst du zum nachschauen<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>Warte mal bitte nen Augenblick<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Reicht die Containernummer?<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>Warte mal bitte.<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Also das ist die Nummer\u2026<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>Warte bitte, ich habe die Verbidnung zur Datenbank noch nicht offen.<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ja woher soll ich das denn wissen?!?<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde:&nbsp;Kannst du mal nachschauen, ob eine Referenz an den Zoll \u00fcbergeben wurde? Service:&nbsp;Ja klar. Kunde:&nbsp;Was brauchst du zum nachschauen Service:&nbsp;Warte mal bitte nen Augenblick Kunde:&nbsp;Reicht die Containernummer? Service:&nbsp;Warte mal bitte. Kunde:&nbsp;Also das ist die Nummer\u2026 Service:&nbsp;Warte bitte, ich habe die Verbidnung zur Datenbank noch nicht offen. Kunde:&nbsp;Ja woher soll ich das denn wissen?!?<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-54","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":1,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"predecessor-version":[{"id":55,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/54\/revisions\/55"}],"wp:attachment":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}