{"id":72,"date":"2011-06-24T15:37:00","date_gmt":"2011-06-24T14:37:00","guid":{"rendered":"https:\/\/edv-verzweifelt.de\/?p=72"},"modified":"2026-03-09T22:55:40","modified_gmt":"2026-03-09T21:55:40","slug":"wozu-ein-papierkorb-wohl-da-ist","status":"publish","type":"post","link":"https:\/\/edv-verzweifelt.de\/index.php\/2011\/06\/24\/wozu-ein-papierkorb-wohl-da-ist\/","title":{"rendered":"Wozu ein Papierkorb wohl da ist?"},"content":{"rendered":"\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ich m\u00f6chte eine Zeile in der Maske&nbsp;<\/em><em>wegwerfen<\/em><em>. Wie mach ich das?<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>In der zu l\u00f6schenden Zeile ist ein Papierkorb abgebildet. Wenn Sie da drauf klicken, l\u00f6scht er die Zeile<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ahja. Wobei das ja bl\u00f6d ist. Wer weis den schon, das ein Papierkorb zum&nbsp;<\/em><em>entfernen<\/em><em>&nbsp;da ist.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde:&nbsp;Ich m\u00f6chte eine Zeile in der Maske&nbsp;wegwerfen. Wie mach ich das? Service:&nbsp;In der zu l\u00f6schenden Zeile ist ein Papierkorb abgebildet. Wenn Sie da drauf klicken, l\u00f6scht er die Zeile Kunde:&nbsp;Ahja. Wobei das ja bl\u00f6d ist. Wer weis den schon, das ein Papierkorb zum&nbsp;entfernen&nbsp;da ist.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-72","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":1,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/72\/revisions"}],"predecessor-version":[{"id":73,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/72\/revisions\/73"}],"wp:attachment":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/media?parent=72"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/categories?post=72"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/tags?post=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}