{"id":82,"date":"2010-10-07T15:46:00","date_gmt":"2010-10-07T14:46:00","guid":{"rendered":"https:\/\/edv-verzweifelt.de\/?p=82"},"modified":"2026-03-09T22:55:51","modified_gmt":"2026-03-09T21:55:51","slug":"gefaehrlicher-kopierer","status":"publish","type":"post","link":"https:\/\/edv-verzweifelt.de\/index.php\/2010\/10\/07\/gefaehrlicher-kopierer\/","title":{"rendered":"Gef\u00e4hrlicher Kopierer"},"content":{"rendered":"\n<p><strong>Kunde:<\/strong>&nbsp;<em>Sie m\u00fcssen mir unbedingt helfen, ich glaube ich habe was gewaltig falsch gemacht.<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>Na schau\u2019n wir mal, was ist denn passiert?<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ich glaube meine Hand ist verstrahlt!<\/em><\/p>\n\n\n\n<p><strong>Service:<\/strong>&nbsp;<em>Was?!? Wie soll dass denn passiert sein?<\/em><\/p>\n\n\n\n<p><strong>Kunde:<\/strong>&nbsp;<em>Ich habe eine Seite auf den Kopierer gelegt und diese mit meiner Hand festgehalten. Nunja und da der Scanner ja mit Radioaktiver Strahlung arbeitet glaube ich, dass meine Hand jetzt verstrahlt ist.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde:&nbsp;Sie m\u00fcssen mir unbedingt helfen, ich glaube ich habe was gewaltig falsch gemacht. Service:&nbsp;Na schau\u2019n wir mal, was ist denn passiert? Kunde:&nbsp;Ich glaube meine Hand ist verstrahlt! Service:&nbsp;Was?!? Wie soll dass denn passiert sein? Kunde:&nbsp;Ich habe eine Seite auf den Kopierer gelegt und diese mit meiner Hand festgehalten. Nunja und da der Scanner ja mit &hellip; <a href=\"https:\/\/edv-verzweifelt.de\/index.php\/2010\/10\/07\/gefaehrlicher-kopierer\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eGef\u00e4hrlicher Kopierer\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-82","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":1,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":83,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/posts\/82\/revisions\/83"}],"wp:attachment":[{"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edv-verzweifelt.de\/index.php\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}